{"id":1767,"date":"2026-04-08T23:16:05","date_gmt":"2026-04-09T06:16:05","guid":{"rendered":"https:\/\/niwniw.net\/bujo\/?p=1767"},"modified":"2026-05-06T00:04:53","modified_gmt":"2026-05-06T07:04:53","slug":"se-desprende","status":"publish","type":"post","link":"https:\/\/niwniw.net\/bujo\/se-desprende\/","title":{"rendered":"Se desprende"},"content":{"rendered":"\n<div class=\"wp-block-group nfd-bg-effect-dots has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Queria poder te falar de todas as coisas que rolam na minha mente<br>me desprende <br>da realidade e aceito<br>que esse mundo nao foi feito pra mim mesmo, entendo<br>nem tudo que desejo eh um desenho<br>meu mundo escuro, e voce quer entrar<br>&#8230; comeco a imaginar<br>todas as coisas lindas que posso desenhar<br>com seu sorriso a me acalentar, vou mergulhar no mar<br>e eu vou te encontrar la no final da peca<br>vou te contar tudo que rola na cabeca<br>todas as ideias que quero desenrolar<br>no baseado que ja to pra bolar<br>me acompanha?<\/p>\n<\/div>\n\n\n\n<div class=\"is-style-nfd-waves-bottom-right wp-block-group has-accent-color has-text-color has-link-color wp-elements-1 has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<ul class=\"wp-block-list\">\n<li class=\"\"><em>A carta de amor nunca enviada<\/em><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Queria poder te falar de todas as coisas que rolam na minha menteme desprende da realidade e aceitoque esse mundo nao foi feito pra mim mesmo, entendonem tudo que desejo eh um desenhomeu mundo escuro, e voce quer entrar&#8230; comeco a imaginartodas as coisas lindas que posso desenharcom seu sorriso a me acalentar, vou mergulhar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-1767","post","type-post","status-publish","format-standard","hentry","category-pumps"],"_links":{"self":[{"href":"https:\/\/niwniw.net\/bujo\/wp-json\/wp\/v2\/posts\/1767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niwniw.net\/bujo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niwniw.net\/bujo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niwniw.net\/bujo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/niwniw.net\/bujo\/wp-json\/wp\/v2\/comments?post=1767"}],"version-history":[{"count":2,"href":"https:\/\/niwniw.net\/bujo\/wp-json\/wp\/v2\/posts\/1767\/revisions"}],"predecessor-version":[{"id":1779,"href":"https:\/\/niwniw.net\/bujo\/wp-json\/wp\/v2\/posts\/1767\/revisions\/1779"}],"wp:attachment":[{"href":"https:\/\/niwniw.net\/bujo\/wp-json\/wp\/v2\/media?parent=1767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niwniw.net\/bujo\/wp-json\/wp\/v2\/categories?post=1767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niwniw.net\/bujo\/wp-json\/wp\/v2\/tags?post=1767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}